
{"id":69536,"date":"2024-02-02T10:52:36","date_gmt":"2024-02-02T10:52:36","guid":{"rendered":"https:\/\/products.hellstengears.com\/en\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/"},"modified":"2026-05-10T04:18:22","modified_gmt":"2026-05-10T04:18:22","slug":"39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795","status":"publish","type":"product","link":"https:\/\/products.hellstengears.com\/fi\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/","title":{"rendered":"39979"},"content":{"rendered":"<p>Hellsten Gears AB is one of Europe&#8217;s largest suppliers of factory refurbished and used gearboxes (automatic gearboxes, DSG gearboxes, manual gearboxes, CVT gearboxes), transfer units, differentials and turbos for passenger cars, motorhomes, commercial vehicles and light utility trucks to most car makes and car models. We have been experts by your side since 1983! With an unique warranty period of 2 years for both factory refurbished and used units, we offer an affordable and safe alternative to original parts. With extensive inventory, correct delivery dates and fast worldwide deliveries, you can count on full assistance from us!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Renoverad utbytesdel &#8211; 2 \u00e5rs garanti<\/p>\n","protected":false},"featured_media":72902,"comment_status":"open","ping_status":"closed","template":"","meta":{"part_no":"39979"},"product_brand":[],"product_cat":[1221],"product_tag":[],"class_list":{"0":"post-69536","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gearbox-man-6-speed-2","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tehdaskunnostettu-GEARBOX MAN. 6 SPEED-2309795-FORD TRANSIT\/TOURNEO CONNECT 13-22<\/title>\n<meta name=\"description\" content=\"Hellsten Gears AB tarjoaa Tehdaskunnostettu %%ct_product_cat%% alkuper\u00e4isell\u00e4 koodilla 2309795for a FORD TRANSIT\/TOURNEO CONNECT 13-22. 2 uoden takuu!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/products.hellstengears.com\/fi\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:locale:alternate\" content=\"fr_FR\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_GB\" \/>\n<meta property=\"og:locale:alternate\" content=\"sv_SE\" \/>\n<meta property=\"og:locale:alternate\" content=\"da_DK\" \/>\n<meta property=\"og:locale:alternate\" content=\"nn_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renovated-GEARBOX MAN. 6 SPEED-2309795-FORD TRANSIT\/TOURNEO CONNECT 13-22\" \/>\n<meta property=\"og:description\" content=\"Hellsten Gears AB offers a Renovated GEARBOX MAN. 6 SPEED with original number 2309795 for a FORD TRANSIT\/TOURNEO CONNECT 13-22. 2 years warranty!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/products.hellstengears.com\/fi\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/\" \/>\n<meta property=\"og:site_name\" content=\"Hellsten Gears | Etsi uudelleenkunnostettuja ja k\u00e4ytettyj\u00e4 vaihteistoja, siirtoyksik\u00f6it\u00e4, etu-\/takatasauspy\u00f6ri\u00e4 ja turboja!\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hellstengearsab\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T04:18:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dropbox.com\/scl\/fi\/w5vm5wy6dp5rzaxwjarkz\/53mWxWw6S1tX18K9VrNSN59IZcbFidTgk0a71dpX.jpg?rlkey=ehfvsklr49v9za9oeuty6lpv7&raw=1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/products.hellstengears.com\\\/en\\\/product\\\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\\\/\",\"url\":\"https:\\\/\\\/products.hellstengears.com\\\/en\\\/product\\\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\\\/\",\"name\":\"Renovated-GEARBOX MAN. 6 SPEED-2309795-FORD TRANSIT\\\/TOURNEO CONNECT 13-22\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/products.hellstengears.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/products.hellstengears.com\\\/en\\\/product\\\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/products.hellstengears.com\\\/en\\\/product\\\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/products.hellstengears.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/53mWxWw6S1tX18K9VrNSN59IZcbFidTgk0a71dpX-2.jpg\",\"datePublished\":\"2024-02-02T10:52:36+00:00\",\"dateModified\":\"2026-05-10T04:18:22+00:00\",\"description\":\"Hellsten Gears AB offers a Renovated GEARBOX MAN. 6 SPEED with original number 2309795 for a FORD TRANSIT\\\/TOURNEO CONNECT 13-22. 2 years warranty!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/products.hellstengears.com\\\/en\\\/product\\\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\\\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/products.hellstengears.com\\\/en\\\/product\\\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/products.hellstengears.com\\\/en\\\/product\\\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\\\/#primaryimage\",\"url\":\"https:\\\/\\\/products.hellstengears.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/53mWxWw6S1tX18K9VrNSN59IZcbFidTgk0a71dpX-2.jpg\",\"contentUrl\":\"https:\\\/\\\/products.hellstengears.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/53mWxWw6S1tX18K9VrNSN59IZcbFidTgk0a71dpX-2.jpg\",\"width\":586,\"height\":434},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/products.hellstengears.com\\\/en\\\/product\\\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/products.hellstengears.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00f8g efter gearkasse dele\",\"item\":\"https:\\\/\\\/products.hellstengears.com\\\/da\\\/search-transmission-parts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"39979\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/products.hellstengears.com\\\/#website\",\"url\":\"https:\\\/\\\/products.hellstengears.com\\\/\",\"name\":\"Hellsten Gears Search Refurbished and Used Products\",\"description\":\"Asiantuntijoita vuodesta 1983\",\"publisher\":{\"@id\":\"https:\\\/\\\/products.hellstengears.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/products.hellstengears.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/products.hellstengears.com\\\/#organization\",\"name\":\"Hellsten Gears AB\",\"url\":\"https:\\\/\\\/products.hellstengears.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/products.hellstengears.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/products.hellstengears.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/01-HellstenGears-logo-main_400-bred.png\",\"contentUrl\":\"https:\\\/\\\/products.hellstengears.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/01-HellstenGears-logo-main_400-bred.png\",\"width\":373,\"height\":92,\"caption\":\"Hellsten Gears AB\"},\"image\":{\"@id\":\"https:\\\/\\\/products.hellstengears.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hellstengearsab\",\"https:\\\/\\\/www.instagram.com\\\/hellstengears\\\/\",\"http:\\\/\\\/linkedin.com\\\/company\\\/hellstengears\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCrkdxgxiDQ31TLRnlNN9kyA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tehdaskunnostettu-GEARBOX MAN. 6 SPEED-2309795-FORD TRANSIT\/TOURNEO CONNECT 13-22","description":"Hellsten Gears AB tarjoaa Tehdaskunnostettu %%ct_product_cat%% alkuper\u00e4isell\u00e4 koodilla 2309795for a FORD TRANSIT\/TOURNEO CONNECT 13-22. 2 uoden takuu!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/products.hellstengears.com\/fi\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/","og_locale":"fi_FI","og_type":"article","og_title":"Renovated-GEARBOX MAN. 6 SPEED-2309795-FORD TRANSIT\/TOURNEO CONNECT 13-22","og_description":"Hellsten Gears AB offers a Renovated GEARBOX MAN. 6 SPEED with original number 2309795 for a FORD TRANSIT\/TOURNEO CONNECT 13-22. 2 years warranty!","og_url":"https:\/\/products.hellstengears.com\/fi\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/","og_site_name":"Hellsten Gears | Etsi uudelleenkunnostettuja ja k\u00e4ytettyj\u00e4 vaihteistoja, siirtoyksik\u00f6it\u00e4, etu-\/takatasauspy\u00f6ri\u00e4 ja turboja!","article_publisher":"https:\/\/www.facebook.com\/hellstengearsab","article_modified_time":"2026-05-10T04:18:22+00:00","og_image":[{"url":"https:\/\/www.dropbox.com\/scl\/fi\/w5vm5wy6dp5rzaxwjarkz\/53mWxWw6S1tX18K9VrNSN59IZcbFidTgk0a71dpX.jpg?rlkey=ehfvsklr49v9za9oeuty6lpv7&raw=1","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/products.hellstengears.com\/en\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/","url":"https:\/\/products.hellstengears.com\/en\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/","name":"Renovated-GEARBOX MAN. 6 SPEED-2309795-FORD TRANSIT\/TOURNEO CONNECT 13-22","isPartOf":{"@id":"https:\/\/products.hellstengears.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/products.hellstengears.com\/en\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/#primaryimage"},"image":{"@id":"https:\/\/products.hellstengears.com\/en\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/#primaryimage"},"thumbnailUrl":"https:\/\/products.hellstengears.com\/wp-content\/uploads\/2024\/11\/53mWxWw6S1tX18K9VrNSN59IZcbFidTgk0a71dpX-2.jpg","datePublished":"2024-02-02T10:52:36+00:00","dateModified":"2026-05-10T04:18:22+00:00","description":"Hellsten Gears AB offers a Renovated GEARBOX MAN. 6 SPEED with original number 2309795 for a FORD TRANSIT\/TOURNEO CONNECT 13-22. 2 years warranty!","breadcrumb":{"@id":"https:\/\/products.hellstengears.com\/en\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/products.hellstengears.com\/en\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/"]}]},{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/products.hellstengears.com\/en\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/#primaryimage","url":"https:\/\/products.hellstengears.com\/wp-content\/uploads\/2024\/11\/53mWxWw6S1tX18K9VrNSN59IZcbFidTgk0a71dpX-2.jpg","contentUrl":"https:\/\/products.hellstengears.com\/wp-content\/uploads\/2024\/11\/53mWxWw6S1tX18K9VrNSN59IZcbFidTgk0a71dpX-2.jpg","width":586,"height":434},{"@type":"BreadcrumbList","@id":"https:\/\/products.hellstengears.com\/en\/product\/39979-ford-transit-tourneo-connect-13-22-gearbox-man-6-speed-2309795\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/products.hellstengears.com\/"},{"@type":"ListItem","position":2,"name":"S\u00f8g efter gearkasse dele","item":"https:\/\/products.hellstengears.com\/da\/search-transmission-parts\/"},{"@type":"ListItem","position":3,"name":"39979"}]},{"@type":"WebSite","@id":"https:\/\/products.hellstengears.com\/#website","url":"https:\/\/products.hellstengears.com\/","name":"Hellsten Gears Search Refurbished and Used Products","description":"Asiantuntijoita vuodesta 1983","publisher":{"@id":"https:\/\/products.hellstengears.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/products.hellstengears.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/products.hellstengears.com\/#organization","name":"Hellsten Gears AB","url":"https:\/\/products.hellstengears.com\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/products.hellstengears.com\/#\/schema\/logo\/image\/","url":"https:\/\/products.hellstengears.com\/wp-content\/uploads\/2021\/11\/01-HellstenGears-logo-main_400-bred.png","contentUrl":"https:\/\/products.hellstengears.com\/wp-content\/uploads\/2021\/11\/01-HellstenGears-logo-main_400-bred.png","width":373,"height":92,"caption":"Hellsten Gears AB"},"image":{"@id":"https:\/\/products.hellstengears.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hellstengearsab","https:\/\/www.instagram.com\/hellstengears\/","http:\/\/linkedin.com\/company\/hellstengears","https:\/\/www.youtube.com\/channel\/UCrkdxgxiDQ31TLRnlNN9kyA"]}]}},"_links":{"self":[{"href":"https:\/\/products.hellstengears.com\/fi\/wp-json\/wp\/v2\/product\/69536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/products.hellstengears.com\/fi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/products.hellstengears.com\/fi\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/products.hellstengears.com\/fi\/wp-json\/wp\/v2\/comments?post=69536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/products.hellstengears.com\/fi\/wp-json\/wp\/v2\/media\/72902"}],"wp:attachment":[{"href":"https:\/\/products.hellstengears.com\/fi\/wp-json\/wp\/v2\/media?parent=69536"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/products.hellstengears.com\/fi\/wp-json\/wp\/v2\/product_brand?post=69536"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/products.hellstengears.com\/fi\/wp-json\/wp\/v2\/product_cat?post=69536"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/products.hellstengears.com\/fi\/wp-json\/wp\/v2\/product_tag?post=69536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}